{"id":142250,"date":"2022-10-04T14:46:56","date_gmt":"2022-10-04T17:46:56","guid":{"rendered":"https:\/\/jornalhoje.inf.br\/wp\/?p=142250"},"modified":"2022-10-04T14:47:00","modified_gmt":"2022-10-04T17:47:00","slug":"emissoes-de-titulos-no-brasil-equivalem-a-135-do-pib","status":"publish","type":"post","link":"https:\/\/jornalhoje.inf.br\/wp\/emissoes-de-titulos-no-brasil-equivalem-a-135-do-pib\/","title":{"rendered":"Emiss\u00f5es de t\u00edtulos no Brasil equivalem a 135% do PIB"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n\n<h4 class=\"wp-block-heading\"><audio src=\"https:\/\/tts-app.ebc.com.br\/media\/tts\/189387.mp3\"><\/h4>\n\n\n\n<p>Andreia Verd\u00e9lio \u2013 Ag\u00eancia Brasil &#8211; As emiss\u00f5es de t\u00edtulos no Brasil equivalem a 135% do Produto Interno Bruto (PIB, soma de todos os bens e servi\u00e7os produzidos no pa\u00eds). Segundo o Banco Central (BC), o volume \u00e9 expressivo e, apesar da emiss\u00e3o de t\u00edtulos privados ser crescente, s\u00e3o preponderantes as emiss\u00f5es de t\u00edtulos p\u00fablicos.<img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.png?id=1486291&amp;o=node\"><img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.gif?id=1486291&amp;o=node\"><\/p>\n\n\n\n<p>De acordo com as estat\u00edsticas divulgadas pelo BC, que integram o&nbsp;<a href=\"https:\/\/www.bcb.gov.br\/publicacoes\/relatorioeconomiabancaria\" target=\"_blank\" rel=\"noreferrer noopener\">Relat\u00f3rio de Economia Banc\u00e1ria<\/a>, no Brasil, em dezembro de 2021, as emiss\u00f5es de t\u00edtulos p\u00fablicos corresponderam a 88% do PIB, enquanto as de t\u00edtulos privados representaram 47% desse total.<\/p>\n\n\n\n<p>Os t\u00edtulos de d\u00edvida s\u00e3o valores mobili\u00e1rios emitidos por empresas ou governos com o objetivo de captar recursos para realiza\u00e7\u00e3o de investimentos ou para condu\u00e7\u00e3o de suas atividades. No \u00e2mbito do governo federal, por exemplo, uma das fontes de capta\u00e7\u00e3o de recursos \u00e9 o Tesouro Direto, criado em 2002 para popularizar tais aplica\u00e7\u00f5es e permitir que pessoas f\u00edsicas adquirissem t\u00edtulos p\u00fablicos diretamente do Tesouro Nacional.<\/p>\n\n\n\n<p>Nesta quinta-feira (6), o BC divulgar\u00e1 a \u00edntegra do Relat\u00f3rio de Economia Banc\u00e1ria de 2021. Assim como hoje, na semana passada, o BC j\u00e1 adiantou alguns boxes de informa\u00e7\u00e3o, que s\u00e3o trechos com estudos especiais dentro do documento. O&nbsp;<a href=\"https:\/\/agenciabrasil.ebc.com.br\/economia\/noticia\/2022-09\/bancos-que-se-digitalizaram-antes-da-pandemia-emprestaram-mais\" target=\"_blank\" rel=\"noreferrer noopener\">mercado de cr\u00e9dito durante a pandemia de covid-19<\/a>&nbsp;e as emiss\u00f5es de&nbsp;<a href=\"https:\/\/agenciabrasil.ebc.com.br\/economia\/noticia\/2022-09\/emissoes-de-titulos-sustentaveis-batem-recorde-no-brasil\" target=\"_blank\" rel=\"noreferrer noopener\">t\u00edtulos relacionados \u00e0 sustentabilidade<\/a>&nbsp;foram os temas tratados pelo BC nos boxes.<\/p>\n\n\n\n<p>J\u00e1 as estat\u00edsticas de t\u00edtulos da d\u00edvida passar\u00e3o a ser divulgadas trimestralmente no&nbsp;<a href=\"https:\/\/www3.bcb.gov.br\/sgspub\/localizarseries\/localizarSeries.do?method=prepararTelaLocalizarSeries\" target=\"_blank\" rel=\"noreferrer noopener\">Sistema Gerenciador de S\u00e9ries Temporais<\/a>, no item Mercados financeiros e de capitais \u2013 Estat\u00edsticas de T\u00edtulos.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Estoque<\/h2>\n\n\n\n<p>Em dezembro do ano passado, o estoque de t\u00edtulos de d\u00edvida emitidos por residentes no pa\u00eds somou R$ 11,7 trilh\u00f5es (135% do PIB). Desse total, 65% (R$ 7,6 trilh\u00f5es) foram emitidos pelo governo geral; 29% por sociedades financeiras (R$3,4 trilh\u00f5es), dos quais 27% por outras sociedades de dep\u00f3sitos e 2% por outras sociedades financeiras e seguradoras; e 6% por sociedades n\u00e3o financeiras (R$ 752 bilh\u00f5es).<\/p>\n\n\n\n<p>As emiss\u00f5es no mercado dom\u00e9stico s\u00e3o preponderantes no estoque de t\u00edtulos, correspondendo a 96% do saldo, em dezembro de 2021. Entre as emiss\u00f5es no mercado internacional, as sociedades n\u00e3o financeiras s\u00e3o as que t\u00eam parcela mais significativa de t\u00edtulos emitidos no exterior (12% de seu estoque), seguidas das sociedades financeiras (5%) e do governo (3%).<\/p>\n\n\n\n<p>De acordo com o BC, em dezembro de 2021, bem como ao longo da s\u00e9rie, a maior parte dos t\u00edtulos tem prazo de emiss\u00e3o superior a dois anos. O setor das sociedades financeiras \u00e9 o que apresenta maior participa\u00e7\u00e3o de t\u00edtulos com vencimentos em prazos menores.<\/p>\n\n\n\n<p>\u201cAo longo da s\u00e9rie, observa-se aumento no prazo dos t\u00edtulos emitidos por sociedades n\u00e3o financeiras (99% do saldo classificado como longo prazo em dezembro de 2021, ante 97% em mar\u00e7o de 2018), relativa estabilidade nos prazos das emiss\u00f5es do governo (98% longo prazo comparado a 99%, nas mesmas datas) e redu\u00e7\u00e3o nos prazos das capta\u00e7\u00f5es de sociedades financeiras (79% longo prazo em dezembro de 2021, ante 83% em mar\u00e7o de 2018)\u201d, diz o documento.<\/p>\n\n\n\n<p>A maior parte dos t\u00edtulos privados (sociedades financeiras e n\u00e3o financeiras) \u00e9 indexada \u00e0 varia\u00e7\u00e3o da taxa b\u00e1sica de juros (Selic). J\u00e1 no saldo de emiss\u00f5es das sociedades n\u00e3o financeiras, \u00e9 crescente a participa\u00e7\u00e3o dos instrumentos indexados \u00e0 infla\u00e7\u00e3o. Para os t\u00edtulos do governo, a segmenta\u00e7\u00e3o por indexadores alinha-se \u00e0 pol\u00edtica fiscal e \u00e9 menos concentrada.<\/p>\n\n\n\n<p>Na classifica\u00e7\u00e3o por moeda de refer\u00eancia, predominam os t\u00edtulos em moeda nacional: 96% do saldo emitido por todos os residentes, em dezembro de 2021.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Detentores<\/h2>\n\n\n\n<p>Em dezembro de 2021, o estoque de t\u00edtulos nas carteiras de detentores residentes alcan\u00e7ou R$ 12,3 trilh\u00f5es (141% do PIB). Desse total, 86% (R$ 10,6 trilh\u00f5es) foram emitidos por residentes (no mercado dom\u00e9stico) e 14% (R$1,7 trilh\u00e3o) por n\u00e3o residentes (no mercado internacional).<\/p>\n\n\n\n<p>Os principais detentores de t\u00edtulos p\u00fablicos s\u00e3o os fundos de investimento monet\u00e1rios (36% do total), seguidos pelo BC (t\u00edtulos destinados \u00e0 execu\u00e7\u00e3o da pol\u00edtica monet\u00e1ria, 30% do total) e pelas outras sociedades de dep\u00f3sitos, 23% (principalmente bancos). Quanto aos t\u00edtulos privados (emitidos por sociedades financeiras e n\u00e3o financeiras), os principais detentores s\u00e3o as sociedades n\u00e3o financeiras e as fam\u00edlias.<\/p>\n\n\n\n<p>Dos t\u00edtulos emitidos por n\u00e3o residentes, a maior parte est\u00e1 inclu\u00edda nas reservas internacionais (R$ 1,6 trilh\u00e3o). O saldo restante (R$ 54 bilh\u00f5es) corresponde a t\u00edtulos adquiridos no exterior por unidades residentes no Brasil, principalmente sociedades financeiras, seguidas por fam\u00edlias e fundos monet\u00e1rios.<\/p>\n\n\n\n<p>O Banco Central iniciou recentemente a produ\u00e7\u00e3o de estat\u00edsticas de t\u00edtulos de d\u00edvida, seguindo o padr\u00e3o metodol\u00f3gico internacional definido no&nbsp;<em>Handbook on Securities Statistics<\/em>. De acordo com a institui\u00e7\u00e3o, as novas estat\u00edsticas alinham-se a iniciativas internacionais de produ\u00e7\u00e3o e dissemina\u00e7\u00e3o de dados, ampliam as informa\u00e7\u00f5es dispon\u00edveis sobre o mercado de t\u00edtulos e contribuem para uma vis\u00e3o mais completa sobre os instrumentos de capta\u00e7\u00e3o de recursos no Brasil.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Andreia Verd\u00e9lio \u2013 Ag\u00eancia Brasil &#8211; As emiss\u00f5es de t\u00edtulos no Brasil equivalem a 135% do Produto Interno Bruto (PIB, soma de todos os bens e servi\u00e7os produzidos no pa\u00eds). Segundo o Banco Central (BC), o volume \u00e9 expressivo e, apesar da emiss\u00e3o de t\u00edtulos privados ser crescente, s\u00e3o preponderantes as emiss\u00f5es de t\u00edtulos p\u00fablicos. De acordo com as estat\u00edsticas divulgadas pelo BC, que integram o&nbsp;Relat\u00f3rio de Economia Banc\u00e1ria, no Brasil, em dezembro de 2021, as emiss\u00f5es de t\u00edtulos p\u00fablicos corresponderam a 88% do PIB, enquanto as de t\u00edtulos privados representaram 47% desse total. Os t\u00edtulos de d\u00edvida s\u00e3o valores mobili\u00e1rios emitidos por empresas ou governos com o objetivo de captar recursos para realiza\u00e7\u00e3o de investimentos ou para condu\u00e7\u00e3o de suas atividades. No \u00e2mbito do governo federal, por exemplo, uma das fontes de capta\u00e7\u00e3o de recursos \u00e9 o Tesouro Direto, criado em 2002 para popularizar tais aplica\u00e7\u00f5es e permitir que pessoas f\u00edsicas adquirissem t\u00edtulos p\u00fablicos diretamente do Tesouro Nacional. Nesta quinta-feira (6), o BC divulgar\u00e1 a \u00edntegra do Relat\u00f3rio de Economia Banc\u00e1ria de 2021. Assim como hoje, na semana passada, o BC j\u00e1 adiantou alguns boxes de informa\u00e7\u00e3o, que s\u00e3o trechos com estudos especiais dentro do documento. O&nbsp;mercado de cr\u00e9dito durante a pandemia de covid-19&nbsp;e as emiss\u00f5es de&nbsp;t\u00edtulos relacionados \u00e0 sustentabilidade&nbsp;foram os temas tratados pelo BC nos boxes. J\u00e1 as estat\u00edsticas de t\u00edtulos da d\u00edvida passar\u00e3o a ser divulgadas trimestralmente no&nbsp;Sistema Gerenciador de S\u00e9ries Temporais, no item Mercados financeiros e de capitais \u2013 Estat\u00edsticas de T\u00edtulos. Estoque Em dezembro do ano passado, o estoque de t\u00edtulos de d\u00edvida emitidos por residentes no pa\u00eds somou R$ 11,7 trilh\u00f5es (135% do PIB). Desse total, 65% (R$ 7,6 trilh\u00f5es) foram emitidos pelo governo geral; 29% por sociedades financeiras (R$3,4 trilh\u00f5es), dos quais 27% por outras sociedades de dep\u00f3sitos e 2% por outras sociedades financeiras e seguradoras; e 6% por sociedades n\u00e3o financeiras (R$ 752 bilh\u00f5es). As emiss\u00f5es no mercado dom\u00e9stico s\u00e3o preponderantes no estoque de t\u00edtulos, correspondendo a 96% do saldo, em dezembro de 2021. Entre as emiss\u00f5es no mercado internacional, as sociedades n\u00e3o financeiras s\u00e3o as que t\u00eam parcela mais significativa de t\u00edtulos emitidos no exterior (12% de seu estoque), seguidas das sociedades financeiras (5%) e do governo (3%). De acordo com o BC, em dezembro de 2021, bem como ao longo da s\u00e9rie, a maior parte dos t\u00edtulos tem prazo de emiss\u00e3o superior a dois anos. O setor das sociedades financeiras \u00e9 o que apresenta maior participa\u00e7\u00e3o de t\u00edtulos com vencimentos em prazos menores. \u201cAo longo da s\u00e9rie, observa-se aumento no prazo dos t\u00edtulos emitidos por sociedades n\u00e3o financeiras (99% do saldo classificado como longo prazo em dezembro de 2021, ante 97% em mar\u00e7o de 2018), relativa estabilidade nos prazos das emiss\u00f5es do governo (98% longo prazo comparado a 99%, nas mesmas datas) e redu\u00e7\u00e3o nos prazos das capta\u00e7\u00f5es de sociedades financeiras (79% longo prazo em dezembro de 2021, ante 83% em mar\u00e7o de 2018)\u201d, diz o documento. A maior parte dos t\u00edtulos privados (sociedades financeiras e n\u00e3o financeiras) \u00e9 indexada \u00e0 varia\u00e7\u00e3o da taxa b\u00e1sica de juros (Selic). J\u00e1 no saldo de emiss\u00f5es das sociedades n\u00e3o financeiras, \u00e9 crescente a participa\u00e7\u00e3o dos instrumentos indexados \u00e0 infla\u00e7\u00e3o. Para os t\u00edtulos do governo, a segmenta\u00e7\u00e3o por indexadores alinha-se \u00e0 pol\u00edtica fiscal e \u00e9 menos concentrada. Na classifica\u00e7\u00e3o por moeda de refer\u00eancia, predominam os t\u00edtulos em moeda nacional: 96% do saldo emitido por todos os residentes, em dezembro de 2021. Detentores Em dezembro de 2021, o estoque de t\u00edtulos nas carteiras de detentores residentes alcan\u00e7ou R$ 12,3 trilh\u00f5es (141% do PIB). Desse total, 86% (R$ 10,6 trilh\u00f5es) foram emitidos por residentes (no mercado dom\u00e9stico) e 14% (R$1,7 trilh\u00e3o) por n\u00e3o residentes (no mercado internacional). Os principais detentores de t\u00edtulos p\u00fablicos s\u00e3o os fundos de investimento monet\u00e1rios (36% do total), seguidos pelo BC (t\u00edtulos destinados \u00e0 execu\u00e7\u00e3o da pol\u00edtica monet\u00e1ria, 30% do total) e pelas outras sociedades de dep\u00f3sitos, 23% (principalmente bancos). Quanto aos t\u00edtulos privados (emitidos por sociedades financeiras e n\u00e3o financeiras), os principais detentores s\u00e3o as sociedades n\u00e3o financeiras e as fam\u00edlias. Dos t\u00edtulos emitidos por n\u00e3o residentes, a maior parte est\u00e1 inclu\u00edda nas reservas internacionais (R$ 1,6 trilh\u00e3o). O saldo restante (R$ 54 bilh\u00f5es) corresponde a t\u00edtulos adquiridos no exterior por unidades residentes no Brasil, principalmente sociedades financeiras, seguidas por fam\u00edlias e fundos monet\u00e1rios. O Banco Central iniciou recentemente a produ\u00e7\u00e3o de estat\u00edsticas de t\u00edtulos de d\u00edvida, seguindo o padr\u00e3o metodol\u00f3gico internacional definido no&nbsp;Handbook on Securities Statistics. De acordo com a institui\u00e7\u00e3o, as novas estat\u00edsticas alinham-se a iniciativas internacionais de produ\u00e7\u00e3o e dissemina\u00e7\u00e3o de dados, ampliam as informa\u00e7\u00f5es dispon\u00edveis sobre o mercado de t\u00edtulos e contribuem para uma vis\u00e3o mais completa sobre os instrumentos de capta\u00e7\u00e3o de recursos no Brasil.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","footnotes":""},"categories":[15],"tags":[],"class_list":["post-142250","post","type-post","status-publish","format-standard","hentry","category-economia"],"_links":{"self":[{"href":"https:\/\/jornalhoje.inf.br\/wp\/wp-json\/wp\/v2\/posts\/142250","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jornalhoje.inf.br\/wp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornalhoje.inf.br\/wp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornalhoje.inf.br\/wp\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/jornalhoje.inf.br\/wp\/wp-json\/wp\/v2\/comments?post=142250"}],"version-history":[{"count":1,"href":"https:\/\/jornalhoje.inf.br\/wp\/wp-json\/wp\/v2\/posts\/142250\/revisions"}],"predecessor-version":[{"id":142251,"href":"https:\/\/jornalhoje.inf.br\/wp\/wp-json\/wp\/v2\/posts\/142250\/revisions\/142251"}],"wp:attachment":[{"href":"https:\/\/jornalhoje.inf.br\/wp\/wp-json\/wp\/v2\/media?parent=142250"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornalhoje.inf.br\/wp\/wp-json\/wp\/v2\/categories?post=142250"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornalhoje.inf.br\/wp\/wp-json\/wp\/v2\/tags?post=142250"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}