{"id":147681,"date":"2023-01-16T11:10:45","date_gmt":"2023-01-16T13:10:45","guid":{"rendered":"https:\/\/jornalhoje.inf.br\/wp\/?p=147681"},"modified":"2023-01-16T11:16:24","modified_gmt":"2023-01-16T13:16:24","slug":"policia-prende-no-rio-mais-um-anestesista-acusado-de-estupro","status":"publish","type":"post","link":"https:\/\/jornalhoje.inf.br\/wp\/policia-prende-no-rio-mais-um-anestesista-acusado-de-estupro\/","title":{"rendered":"Pol\u00edcia prende no Rio mais um anestesista acusado de estupro"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n\n<p>Akemi Nitahara \u2013 Ag\u00eancia Brasil &#8211; O m\u00e9dico anestesista colombiano Andres Eduardo Onate Carrillo, acusado de estupro de vulner\u00e1vel, foi preso hoje (16), no Rio de Janeiro. Segundo a Pol\u00edcia Civil, ele foi preso por agentes da Delegacia da Crian\u00e7a e do Adolescente V\u00edtima (DCAV), na pr\u00f3pria resid\u00eancia, na Barra da Tijuca.<img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.png?id=1504468&amp;o=node\"><img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.gif?id=1504468&amp;o=node\"><\/p>\n\n\n\n<p>Os policiais cumpriram mandados de pris\u00e3o e de busca e apreens\u00e3o. Carrillo \u00e9 suspeito de estuprar pacientes sedadas, durante cirurgias, em hospitais das redes p\u00fablica e particular. A Pol\u00edcia Civil informou que ele tinha o h\u00e1bito de filmar o ato do crime e colecionar as imagens.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Cenas de abuso<\/h2>\n\n\n\n<p>O colombiano responde tamb\u00e9m a inqu\u00e9rito por produ\u00e7\u00e3o e armazenamento de cenas de abuso infantojuvenil. Foram encontrados nos equipamentos eletr\u00f4nicos do m\u00e9dico mais de 20 mil arquivos com imagens de abuso sexual envolvendo crian\u00e7as e adolescentes.<\/p>\n\n\n\n<p>\u201cA an\u00e1lise do material chamou a aten\u00e7\u00e3o pela gravidade e quantidade de arquivos, que inclu\u00edam at\u00e9 beb\u00eas com menos de um ano de vida\u201d, informou a pol\u00edcia, em nota.<\/p>\n\n\n\n<p>As investiga\u00e7\u00f5es come\u00e7aram no m\u00eas passado, com o compartilhamento de informa\u00e7\u00f5es entre o Servi\u00e7o de Repress\u00e3o a Crimes de \u00d3dio e Pornografia Infantil (Sercopi) da Pol\u00edcia Federal com a Intelig\u00eancia do 2\u00ba Departamento de Pol\u00edcia de \u00c1rea (DPA) da Pol\u00edcia Civil.<\/p>\n\n\n\n<p>Os pr\u00f3ximos passos da investiga\u00e7\u00e3o incluem levantar todas as unidades em que o m\u00e9dico trabalha para encontrar novas poss\u00edveis v\u00edtimas, al\u00e9m de analisar o material apreendido.<\/p>\n\n\n\n<p>Em julho do ano passado, o anestesista Giovanni Quintella Bezerra foi preso ap\u00f3s estuprar uma mulher durante o parto no centro cir\u00fargico do Hospital da Mulher Heloneida Studart, em S\u00e3o Jo\u00e3o de Meriti, na Baixada Fluminense. Ele est\u00e1 preso e<a href=\"http:\/\/agenciabrasil.ebc.com.br\/justica\/noticia\/2022-11\/justica-nega-pedido-de-soltura-para-anestesista-acusado-de-estupro#\" target=\"_blank\" rel=\"noreferrer noopener\">&nbsp;a justi\u00e7a negou o&nbsp;<em>habeas corpus<\/em><\/a>&nbsp;em novembro.<\/p>\n\n\n\n<p>Edi\u00e7\u00e3o: Kleber Sampaio<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Akemi Nitahara \u2013 Ag\u00eancia Brasil &#8211; O m\u00e9dico anestesista colombiano Andres Eduardo Onate Carrillo, acusado de estupro de vulner\u00e1vel, foi preso hoje (16), no Rio de Janeiro. Segundo a Pol\u00edcia Civil, ele foi preso por agentes da Delegacia da Crian\u00e7a e do Adolescente V\u00edtima (DCAV), na pr\u00f3pria resid\u00eancia, na Barra da Tijuca. Os policiais cumpriram mandados de pris\u00e3o e de busca e apreens\u00e3o. Carrillo \u00e9 suspeito de estuprar pacientes sedadas, durante cirurgias, em hospitais das redes p\u00fablica e particular. A Pol\u00edcia Civil informou que ele tinha o h\u00e1bito de filmar o ato do crime e colecionar as imagens. Cenas de abuso O colombiano responde tamb\u00e9m a inqu\u00e9rito por produ\u00e7\u00e3o e armazenamento de cenas de abuso infantojuvenil. Foram encontrados nos equipamentos eletr\u00f4nicos do m\u00e9dico mais de 20 mil arquivos com imagens de abuso sexual envolvendo crian\u00e7as e adolescentes. \u201cA an\u00e1lise do material chamou a aten\u00e7\u00e3o pela gravidade e quantidade de arquivos, que inclu\u00edam at\u00e9 beb\u00eas com menos de um ano de vida\u201d, informou a pol\u00edcia, em nota. As investiga\u00e7\u00f5es come\u00e7aram no m\u00eas passado, com o compartilhamento de informa\u00e7\u00f5es entre o Servi\u00e7o de Repress\u00e3o a Crimes de \u00d3dio e Pornografia Infantil (Sercopi) da Pol\u00edcia Federal com a Intelig\u00eancia do 2\u00ba Departamento de Pol\u00edcia de \u00c1rea (DPA) da Pol\u00edcia Civil. Os pr\u00f3ximos passos da investiga\u00e7\u00e3o incluem levantar todas as unidades em que o m\u00e9dico trabalha para encontrar novas poss\u00edveis v\u00edtimas, al\u00e9m de analisar o material apreendido. Em julho do ano passado, o anestesista Giovanni Quintella Bezerra foi preso ap\u00f3s estuprar uma mulher durante o parto no centro cir\u00fargico do Hospital da Mulher Heloneida Studart, em S\u00e3o Jo\u00e3o de Meriti, na Baixada Fluminense. Ele est\u00e1 preso e&nbsp;a justi\u00e7a negou o&nbsp;habeas corpus&nbsp;em novembro. Edi\u00e7\u00e3o: Kleber Sampaio<\/p>\n","protected":false},"author":3,"featured_media":147683,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","footnotes":""},"categories":[16,31],"tags":[],"class_list":["post-147681","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral","category-principais"],"_links":{"self":[{"href":"https:\/\/jornalhoje.inf.br\/wp\/wp-json\/wp\/v2\/posts\/147681","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jornalhoje.inf.br\/wp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornalhoje.inf.br\/wp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornalhoje.inf.br\/wp\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/jornalhoje.inf.br\/wp\/wp-json\/wp\/v2\/comments?post=147681"}],"version-history":[{"count":1,"href":"https:\/\/jornalhoje.inf.br\/wp\/wp-json\/wp\/v2\/posts\/147681\/revisions"}],"predecessor-version":[{"id":147682,"href":"https:\/\/jornalhoje.inf.br\/wp\/wp-json\/wp\/v2\/posts\/147681\/revisions\/147682"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jornalhoje.inf.br\/wp\/wp-json\/wp\/v2\/media\/147683"}],"wp:attachment":[{"href":"https:\/\/jornalhoje.inf.br\/wp\/wp-json\/wp\/v2\/media?parent=147681"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornalhoje.inf.br\/wp\/wp-json\/wp\/v2\/categories?post=147681"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornalhoje.inf.br\/wp\/wp-json\/wp\/v2\/tags?post=147681"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}