{"id":150011,"date":"2023-02-26T08:28:49","date_gmt":"2023-02-26T11:28:49","guid":{"rendered":"https:\/\/jornalhoje.inf.br\/wp\/?p=150011"},"modified":"2023-02-26T08:48:41","modified_gmt":"2023-02-26T11:48:41","slug":"obra-interrompe-producao-de-agua-na-represa-tingua","status":"publish","type":"post","link":"https:\/\/jornalhoje.inf.br\/wp\/obra-interrompe-producao-de-agua-na-represa-tingua\/","title":{"rendered":"Obra interrompe produ\u00e7\u00e3o de \u00e1gua na bela Represa Tingu\u00e1"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n\n<p><em>Interven\u00e7\u00e3o faz parte das etapas de constru\u00e7\u00e3o da nova ETA Tingu\u00e1<\/em> &#8211; A Cedae vai realizar, na ter\u00e7a-feira (28\/2), a interliga\u00e7\u00e3o de tubula\u00e7\u00e3o \u00e0 nova Esta\u00e7\u00e3o de Tratamento de \u00c1gua (ETA) Tingu\u00e1, em Nova Igua\u00e7u. A a\u00e7\u00e3o ser\u00e1 iniciada \u00e0s 7h e dever\u00e1 ser conclu\u00edda at\u00e9 1h da madrugada de quarta-feira (1\/3). Para executar o servi\u00e7o, ser\u00e1 preciso paralisar a opera\u00e7\u00e3o da Represa Tingu\u00e1.<\/p>\n\n\n\n<p>A obra vai demandar a interdi\u00e7\u00e3o de parte da Estrada Zumbi dos Palmares, na altura do n\u00famero 236, no bairro Tingu\u00e1. Na segunda-feira (27\/2), equipes do Trabalho Social da Cedae estar\u00e3o na localidade orientando os moradores sobre a interven\u00e7\u00e3o que ser\u00e1 feita.<\/p>\n\n\n\n<p>A produ\u00e7\u00e3o de \u00e1gua da Represa Tingu\u00e1 ser\u00e1 retomada logo ap\u00f3s a conclus\u00e3o da obra. A concession\u00e1ria \u00c1guas do Rio, respons\u00e1vel pela distribui\u00e7\u00e3o de \u00e1gua em Nova Igua\u00e7u, j\u00e1 foi comunicada.<\/p>\n\n\n\n<p><strong>Sobre a ETA Tingu\u00e1<\/strong><\/p>\n\n\n\n<p>A nova ETA Tingu\u00e1, em Nova Igua\u00e7u, beneficiar\u00e1 cerca de 150 mil moradores da regi\u00e3o. Com vaz\u00e3o de 650 litros por segundo (l\/s), a unidade ser\u00e1 operada de forma automatizada por meio de tecnologia capaz de monitorar, em tempo real, todas as etapas do tratamento de \u00e1gua.<\/p>\n\n\n\n<p>A ETA Tingu\u00e1 faz parte do Sistema Acari, composto por cinco represas (S\u00e3o Pedro, Rio d\u2019Ouro, Tingu\u00e1, Xer\u00e9m e Mantiquira) que abastecem parte da Baixada Fluminense.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/jornalhoje.inf.br\/wp\/wp-content\/uploads\/2023\/02\/1_tratamento_agua_30-25935049.webp\" alt=\"\" class=\"wp-image-150015\" width=\"433\" height=\"243\" srcset=\"https:\/\/jornalhoje.inf.br\/wp\/wp-content\/uploads\/2023\/02\/1_tratamento_agua_30-25935049.webp 764w, https:\/\/jornalhoje.inf.br\/wp\/wp-content\/uploads\/2023\/02\/1_tratamento_agua_30-25935049-300x168.webp 300w\" sizes=\"(max-width: 433px) 100vw, 433px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img decoding=\"async\" src=\"https:\/\/jornalhoje.inf.br\/wp\/wp-content\/uploads\/2023\/02\/nova_iguacu_tingua_fonte__ninfas_douro_ika21981_1392408391.jpg\" alt=\"\" class=\"wp-image-150017\" width=\"432\" height=\"287\" srcset=\"https:\/\/jornalhoje.inf.br\/wp\/wp-content\/uploads\/2023\/02\/nova_iguacu_tingua_fonte__ninfas_douro_ika21981_1392408391.jpg 800w, https:\/\/jornalhoje.inf.br\/wp\/wp-content\/uploads\/2023\/02\/nova_iguacu_tingua_fonte__ninfas_douro_ika21981_1392408391-300x200.jpg 300w, https:\/\/jornalhoje.inf.br\/wp\/wp-content\/uploads\/2023\/02\/nova_iguacu_tingua_fonte__ninfas_douro_ika21981_1392408391-768x511.jpg 768w\" sizes=\"(max-width: 432px) 100vw, 432px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img decoding=\"async\" src=\"https:\/\/jornalhoje.inf.br\/wp\/wp-content\/uploads\/2023\/02\/Represa-de-Tingua-Alunos-visitam.jpg\" alt=\"\" class=\"wp-image-150018\" width=\"657\" height=\"398\" srcset=\"https:\/\/jornalhoje.inf.br\/wp\/wp-content\/uploads\/2023\/02\/Represa-de-Tingua-Alunos-visitam.jpg 873w, https:\/\/jornalhoje.inf.br\/wp\/wp-content\/uploads\/2023\/02\/Represa-de-Tingua-Alunos-visitam-300x182.jpg 300w, https:\/\/jornalhoje.inf.br\/wp\/wp-content\/uploads\/2023\/02\/Represa-de-Tingua-Alunos-visitam-768x466.jpg 768w\" sizes=\"(max-width: 657px) 100vw, 657px\" \/><\/figure>\n\n\n\n<p>Alunos de escola p\u00fablica municipal visitam a represa de Tingu\u00e1<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Interven\u00e7\u00e3o faz parte das etapas de constru\u00e7\u00e3o da nova ETA Tingu\u00e1 &#8211; A Cedae vai realizar, na ter\u00e7a-feira (28\/2), a interliga\u00e7\u00e3o de tubula\u00e7\u00e3o \u00e0 nova Esta\u00e7\u00e3o de Tratamento de \u00c1gua (ETA) Tingu\u00e1, em Nova Igua\u00e7u. A a\u00e7\u00e3o ser\u00e1 iniciada \u00e0s 7h e dever\u00e1 ser conclu\u00edda at\u00e9 1h da madrugada de quarta-feira (1\/3). Para executar o servi\u00e7o, ser\u00e1 preciso paralisar a opera\u00e7\u00e3o da Represa Tingu\u00e1. A obra vai demandar a interdi\u00e7\u00e3o de parte da Estrada Zumbi dos Palmares, na altura do n\u00famero 236, no bairro Tingu\u00e1. Na segunda-feira (27\/2), equipes do Trabalho Social da Cedae estar\u00e3o na localidade orientando os moradores sobre a interven\u00e7\u00e3o que ser\u00e1 feita. A produ\u00e7\u00e3o de \u00e1gua da Represa Tingu\u00e1 ser\u00e1 retomada logo ap\u00f3s a conclus\u00e3o da obra. A concession\u00e1ria \u00c1guas do Rio, respons\u00e1vel pela distribui\u00e7\u00e3o de \u00e1gua em Nova Igua\u00e7u, j\u00e1 foi comunicada. Sobre a ETA Tingu\u00e1 A nova ETA Tingu\u00e1, em Nova Igua\u00e7u, beneficiar\u00e1 cerca de 150 mil moradores da regi\u00e3o. Com vaz\u00e3o de 650 litros por segundo (l\/s), a unidade ser\u00e1 operada de forma automatizada por meio de tecnologia capaz de monitorar, em tempo real, todas as etapas do tratamento de \u00e1gua. A ETA Tingu\u00e1 faz parte do Sistema Acari, composto por cinco represas (S\u00e3o Pedro, Rio d\u2019Ouro, Tingu\u00e1, Xer\u00e9m e Mantiquira) que abastecem parte da Baixada Fluminense. Alunos de escola p\u00fablica municipal visitam a represa de Tingu\u00e1<\/p>\n","protected":false},"author":3,"featured_media":150013,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","footnotes":""},"categories":[13,30,31],"tags":[],"class_list":["post-150011","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-baixada","category-destaques","category-principais"],"_links":{"self":[{"href":"https:\/\/jornalhoje.inf.br\/wp\/wp-json\/wp\/v2\/posts\/150011","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jornalhoje.inf.br\/wp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornalhoje.inf.br\/wp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornalhoje.inf.br\/wp\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/jornalhoje.inf.br\/wp\/wp-json\/wp\/v2\/comments?post=150011"}],"version-history":[{"count":4,"href":"https:\/\/jornalhoje.inf.br\/wp\/wp-json\/wp\/v2\/posts\/150011\/revisions"}],"predecessor-version":[{"id":150020,"href":"https:\/\/jornalhoje.inf.br\/wp\/wp-json\/wp\/v2\/posts\/150011\/revisions\/150020"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jornalhoje.inf.br\/wp\/wp-json\/wp\/v2\/media\/150013"}],"wp:attachment":[{"href":"https:\/\/jornalhoje.inf.br\/wp\/wp-json\/wp\/v2\/media?parent=150011"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornalhoje.inf.br\/wp\/wp-json\/wp\/v2\/categories?post=150011"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornalhoje.inf.br\/wp\/wp-json\/wp\/v2\/tags?post=150011"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}