{"id":97097,"date":"2019-01-18T23:25:56","date_gmt":"2019-01-19T01:25:56","guid":{"rendered":"https:\/\/jornalhoje.inf.br\/wp\/?p=97097"},"modified":"2019-01-18T23:25:56","modified_gmt":"2019-01-19T01:25:56","slug":"diniz-nao-ha-prazo-definido-para-esperar-por-ganso","status":"publish","type":"post","link":"https:\/\/jornalhoje.inf.br\/wp\/diniz-nao-ha-prazo-definido-para-esperar-por-ganso\/","title":{"rendered":"Diniz: n\u00e3o h\u00e1 prazo definido  para esperar por Ganso"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n<figure id=\"attachment_97098\" aria-describedby=\"caption-attachment-97098\" style=\"width: 300px\" class=\"wp-caption alignleft\"><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-97098 size-medium\" src=\"https:\/\/jornalhoje.inf.br\/wp\/wp-content\/uploads\/2019\/01\/190118-H81-300x196.jpeg\" alt=\"\" width=\"300\" height=\"196\" srcset=\"https:\/\/jornalhoje.inf.br\/wp\/wp-content\/uploads\/2019\/01\/190118-H81-300x196.jpeg 300w, https:\/\/jornalhoje.inf.br\/wp\/wp-content\/uploads\/2019\/01\/190118-H81.jpeg 500w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><figcaption id=\"caption-attachment-97098\" class=\"wp-caption-text\">T\u00e9cnico comenta negocia\u00e7\u00e3o com meia do Sevilla, fala que tamb\u00e9m deseja contratar Nen\u00ea e projeta estreia no Carioca diante do Volta Redonda<br \/>(Felipe Siqueira\/GloboEsporte.com)<\/figcaption><\/figure>\n<p>Fernando Diniz est\u00e1 animado com a possibilidade de contar com Paulo Henrique Ganso. Apesar da dificuldade de negocia\u00e7\u00e3o com o Sevilla, o treinador revelou que o Fluminense n\u00e3o estabeleceu um prazo para esperar pela contrata\u00e7\u00e3o do meia. Enquanto n\u00e3o h\u00e1 um desfecho, o t\u00e9cnico prometeu uma equipe competitiva, a come\u00e7ar por s\u00e1bado, diante do Volta Redonda, na estreia do Carioca.<br \/>\n&#8211; A expectativa \u00e9 muito boa. A hist\u00f3ria come\u00e7ou com uma rela\u00e7\u00e3o que tive com o Ganso. Na \u00e9poca do Audax, jogamos contra. Falei com ele, ele est\u00e1 animado para vir. Tem coisas que escapam de mim e ao Fluminense. Tem outras coisas envolvidas. Se ele puder vir, ser\u00e1 um refor\u00e7o de peso. Estou atento a isso, mas a gente n\u00e3o tem prazo definido. N\u00e3o depende da gente. O interesse \u00e9 m\u00fatuo, mas tem outras pessoas que t\u00eam de decidir &#8211; disse Diniz.<\/p>\n<p>Recentemente,\u00a0o GloboEsporte.com revelou que o treinador havia telefonado ao atleta. Isso ocorreu antes de o Sevilla complicar a negocia\u00e7\u00e3o com o brasileiro.\u00a0Agora, o time espanhol desistiu de emprest\u00e1-lo e s\u00f3 aceita vend\u00ea-lo.<br \/>\n&#8211; O Ganso, eu acho, \u00e9 um dos maiores talentos que o futebol brasileiro produziu nos \u00faltimos anos. O que falta a ele \u00e9 dar continuidade e jogar com const\u00e2ncia. Acredito que, caso a gente trabalhe junto, iremos oferecer isso a ele &#8211; completou Diniz.<br \/>\nNen\u00ea, do S\u00e3o Paulo, \u00e9 outro meia que interesse. A posi\u00e7\u00e3o, ali\u00e1s, \u00e9 a mais carente do elenco. Por\u00e9m, o S\u00e3o Paulo, neste primeiro momento, n\u00e3o parece disposto a liber\u00e1-lo. Diniz comentou:<br \/>\n&#8211; Jogador bom e que faz diferen\u00e7a sempre tem possibilidade. \u00c9 dif\u00edcil de acontecer. Todo mundo sabe das dificuldades financeiras da dire\u00e7\u00e3o e da responsabilidade de respeitar o or\u00e7amento. Ent\u00e3o, se a gente puder ter os dois, seria \u00f3timo.<br \/>\nSobre o trabalho na pr\u00e9-temporada, Diniz se mostrou animado com o apresentado pelos jogadores.<br \/>\n&#8211; Esperamos apresentar um time competitivo. A pr\u00e9-temporada foi importante, os jogadores se dedicaram muito. Me sinto honrado em retornar a uma cansa onde fui feliz. Antes de falar de t\u00edtulo, temos de falar trabalho e seriedade. Temos um ano inteiro para construir um time competitivo e que consiga fazer jus \u00e0 tradi\u00e7\u00e3o do Fluminense &#8211; encerrou o t\u00e9cnico.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fernando Diniz est\u00e1 animado com a possibilidade de contar com Paulo Henrique Ganso. Apesar da dificuldade de negocia\u00e7\u00e3o com o Sevilla, o treinador revelou que o Fluminense n\u00e3o estabeleceu um prazo para esperar pela contrata\u00e7\u00e3o do meia. Enquanto n\u00e3o h\u00e1 um desfecho, o t\u00e9cnico prometeu uma equipe competitiva, a come\u00e7ar por s\u00e1bado, diante do Volta Redonda, na estreia do Carioca. &#8211; A expectativa \u00e9 muito boa. A hist\u00f3ria come\u00e7ou com uma rela\u00e7\u00e3o que tive com o Ganso. Na \u00e9poca do Audax, jogamos contra. Falei com ele, ele est\u00e1 animado para vir. Tem coisas que escapam de mim e ao Fluminense. Tem outras coisas envolvidas. Se ele puder vir, ser\u00e1 um refor\u00e7o de peso. Estou atento a isso, mas a gente n\u00e3o tem prazo definido. N\u00e3o depende da gente. O interesse \u00e9 m\u00fatuo, mas tem outras pessoas que t\u00eam de decidir &#8211; disse Diniz. Recentemente,\u00a0o GloboEsporte.com revelou que o treinador havia telefonado ao atleta. Isso ocorreu antes de o Sevilla complicar a negocia\u00e7\u00e3o com o brasileiro.\u00a0Agora, o time espanhol desistiu de emprest\u00e1-lo e s\u00f3 aceita vend\u00ea-lo. &#8211; O Ganso, eu acho, \u00e9 um dos maiores talentos que o futebol brasileiro produziu nos \u00faltimos anos. O que falta a ele \u00e9 dar continuidade e jogar com const\u00e2ncia. Acredito que, caso a gente trabalhe junto, iremos oferecer isso a ele &#8211; completou Diniz. Nen\u00ea, do S\u00e3o Paulo, \u00e9 outro meia que interesse. A posi\u00e7\u00e3o, ali\u00e1s, \u00e9 a mais carente do elenco. Por\u00e9m, o S\u00e3o Paulo, neste primeiro momento, n\u00e3o parece disposto a liber\u00e1-lo. Diniz comentou: &#8211; Jogador bom e que faz diferen\u00e7a sempre tem possibilidade. \u00c9 dif\u00edcil de acontecer. Todo mundo sabe das dificuldades financeiras da dire\u00e7\u00e3o e da responsabilidade de respeitar o or\u00e7amento. Ent\u00e3o, se a gente puder ter os dois, seria \u00f3timo. Sobre o trabalho na pr\u00e9-temporada, Diniz se mostrou animado com o apresentado pelos jogadores. &#8211; Esperamos apresentar um time competitivo. A pr\u00e9-temporada foi importante, os jogadores se dedicaram muito. Me sinto honrado em retornar a uma cansa onde fui feliz. Antes de falar de t\u00edtulo, temos de falar trabalho e seriedade. Temos um ano inteiro para construir um time competitivo e que consiga fazer jus \u00e0 tradi\u00e7\u00e3o do Fluminense &#8211; encerrou o t\u00e9cnico.<\/p>\n","protected":false},"author":21,"featured_media":97098,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","footnotes":""},"categories":[30,17,31],"tags":[],"class_list":["post-97097","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaques","category-esportes","category-principais"],"_links":{"self":[{"href":"https:\/\/jornalhoje.inf.br\/wp\/wp-json\/wp\/v2\/posts\/97097","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jornalhoje.inf.br\/wp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornalhoje.inf.br\/wp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornalhoje.inf.br\/wp\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/jornalhoje.inf.br\/wp\/wp-json\/wp\/v2\/comments?post=97097"}],"version-history":[{"count":1,"href":"https:\/\/jornalhoje.inf.br\/wp\/wp-json\/wp\/v2\/posts\/97097\/revisions"}],"predecessor-version":[{"id":97099,"href":"https:\/\/jornalhoje.inf.br\/wp\/wp-json\/wp\/v2\/posts\/97097\/revisions\/97099"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jornalhoje.inf.br\/wp\/wp-json\/wp\/v2\/media\/97098"}],"wp:attachment":[{"href":"https:\/\/jornalhoje.inf.br\/wp\/wp-json\/wp\/v2\/media?parent=97097"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornalhoje.inf.br\/wp\/wp-json\/wp\/v2\/categories?post=97097"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornalhoje.inf.br\/wp\/wp-json\/wp\/v2\/tags?post=97097"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}