{"id":99423,"date":"2019-06-04T13:10:42","date_gmt":"2019-06-04T16:10:42","guid":{"rendered":"https:\/\/jornalhoje.inf.br\/wp\/?p=99423"},"modified":"2019-06-04T13:10:42","modified_gmt":"2019-06-04T16:10:42","slug":"trupe-circense-leva-atividades-culturais-gratuitas-para-caxias","status":"publish","type":"post","link":"https:\/\/jornalhoje.inf.br\/wp\/trupe-circense-leva-atividades-culturais-gratuitas-para-caxias\/","title":{"rendered":"Trupe circense leva atividades culturais gratuitas para Caxias"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n<figure id=\"attachment_99424\" aria-describedby=\"caption-attachment-99424\" style=\"width: 300px\" class=\"wp-caption alignleft\"><img fetchpriority=\"high\" decoding=\"async\" class=\"size-medium wp-image-99424\" src=\"https:\/\/jornalhoje.inf.br\/wp\/wp-content\/uploads\/2019\/06\/Grupo-Off-Sina-300x225.jpeg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/jornalhoje.inf.br\/wp\/wp-content\/uploads\/2019\/06\/Grupo-Off-Sina-300x225.jpeg 300w, https:\/\/jornalhoje.inf.br\/wp\/wp-content\/uploads\/2019\/06\/Grupo-Off-Sina-768x575.jpeg 768w, https:\/\/jornalhoje.inf.br\/wp\/wp-content\/uploads\/2019\/06\/Grupo-Off-Sina-1024x767.jpeg 1024w, https:\/\/jornalhoje.inf.br\/wp\/wp-content\/uploads\/2019\/06\/Grupo-Off-Sina.jpeg 1280w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><figcaption id=\"caption-attachment-99424\" class=\"wp-caption-text\">Projeto \u201cDe Olho no Duto\u201d, investimento social da Transpetro levar\u00e1 a arte do palha\u00e7o para as comunidades Saraiva, Figueira e Pilar, com atividades nos dias 7, 21 e 29<\/figcaption><\/figure>\n<p>O Instituto Cultural Escola Livre de Palha\u00e7os &#8211; Eslipa apresentar\u00e1, nos dias 7, 21 e 29 de junho, em Saraiva, Figueira e Pilar (Duque de Caxias), o projeto \u201cDe Olho no Duto\u201d, que conta com\u00a0investimento social da Transpetro. A iniciativa tem como foco principal oferecer aos moradores dos bairros atividades culturais gratuitas, com espet\u00e1culo e roda de conversa. A programa\u00e7\u00e3o come\u00e7a \u00e0s 9h45.<\/p>\n<p>A apresenta\u00e7\u00e3o do espet\u00e1culo &#8220;L\u00e1 vem o circo&#8221;, que mostra uma trupe de palha\u00e7os chegando numa comunidade e buscando um lugar para montar seu Circo Pinico sem Tampa, abre a programa\u00e7\u00e3o.\u00a0\u201cL\u00e1 vem o circo\u201d\u00a0mostra a peculiar rela\u00e7\u00e3o entre os palha\u00e7os, permeada por situa\u00e7\u00f5es de amizade, conflitos e conquistas.\u00a0Logo ap\u00f3s, os moradores participar\u00e3o da roda de conversa, um bate-papo entre os artistas e moradores, ap\u00f3s o t\u00e9rmino da apresenta\u00e7\u00e3o, para identificar as manifesta\u00e7\u00f5es art\u00edsticas existentes nas comunidades e fortalecer as iniciativas culturais dos moradores.<\/p>\n<p>Os diretores e artistas da Eslipa, Richard Riguetti e Lilian Moraes, destacam que o objetivo do projeto \u00e9 promover a cidadania, os direitos humanos, a inclus\u00e3o social e o respeito \u00e0 diversidade humana e cultural das comunidades. \u201cTodas as atividades do projeto ser\u00e3o realizadas em espa\u00e7os p\u00fablicos abertos, com o compromisso de promover o di\u00e1logo permanente entre os artistas e a comunidade, para identificar, potencializar e valorizar as iniciativas art\u00edsticas e culturais de cada regi\u00e3o\u201d, explicam os artistas.<\/p>\n<p>Para a Transpetro, &#8220;O projeto tem premissas b\u00e1sicas de transforma\u00e7\u00e3o social, calcadas na forma\u00e7\u00e3o cidad\u00e3, no engajamento\u00a0 das comunidades, na atua\u00e7\u00e3o forte da divulga\u00e7\u00e3o dos canais de comunica\u00e7\u00e3o e a\u00e7\u00f5es e informa\u00e7\u00f5es preventivas, al\u00e9m do desenvolvimento do senso de pertencimento local\u201d.<\/p>\n<p>O projeto \u201cDe Olho no Duto\u201d contemplar\u00e1 39 comunidades do Rio de Janeiro, vizinhas \u00e0s instala\u00e7\u00f5es dos dutos da Transpetro, entre elas: Itagua\u00ed, Mangaratiba, Nova Igua\u00e7u, Maca\u00e9, Quissam\u00e3, Mag\u00e9, Paracambi, Miguel Pereira, Guapimirim, Rio das Ostras, Carapebus, Campos e Casimiro de Abreu, Paracambi. As apresenta\u00e7\u00f5es acontecer\u00e3o durante um per\u00edodo de dois anos, envolvendo mais de 600 atividades art\u00edsticas, como oficinas, cortejos, espet\u00e1culos e rodas de conversas. Ao todo, estima-se que 150 mil pessoas de todas as idades ser\u00e3o favorecidas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Instituto Cultural Escola Livre de Palha\u00e7os &#8211; Eslipa apresentar\u00e1, nos dias 7, 21 e 29 de junho, em Saraiva, Figueira e Pilar (Duque de Caxias), o projeto \u201cDe Olho no Duto\u201d, que conta com\u00a0investimento social da Transpetro. A iniciativa tem como foco principal oferecer aos moradores dos bairros atividades culturais gratuitas, com espet\u00e1culo e roda de conversa. A programa\u00e7\u00e3o come\u00e7a \u00e0s 9h45. A apresenta\u00e7\u00e3o do espet\u00e1culo &#8220;L\u00e1 vem o circo&#8221;, que mostra uma trupe de palha\u00e7os chegando numa comunidade e buscando um lugar para montar seu Circo Pinico sem Tampa, abre a programa\u00e7\u00e3o.\u00a0\u201cL\u00e1 vem o circo\u201d\u00a0mostra a peculiar rela\u00e7\u00e3o entre os palha\u00e7os, permeada por situa\u00e7\u00f5es de amizade, conflitos e conquistas.\u00a0Logo ap\u00f3s, os moradores participar\u00e3o da roda de conversa, um bate-papo entre os artistas e moradores, ap\u00f3s o t\u00e9rmino da apresenta\u00e7\u00e3o, para identificar as manifesta\u00e7\u00f5es art\u00edsticas existentes nas comunidades e fortalecer as iniciativas culturais dos moradores. Os diretores e artistas da Eslipa, Richard Riguetti e Lilian Moraes, destacam que o objetivo do projeto \u00e9 promover a cidadania, os direitos humanos, a inclus\u00e3o social e o respeito \u00e0 diversidade humana e cultural das comunidades. \u201cTodas as atividades do projeto ser\u00e3o realizadas em espa\u00e7os p\u00fablicos abertos, com o compromisso de promover o di\u00e1logo permanente entre os artistas e a comunidade, para identificar, potencializar e valorizar as iniciativas art\u00edsticas e culturais de cada regi\u00e3o\u201d, explicam os artistas. Para a Transpetro, &#8220;O projeto tem premissas b\u00e1sicas de transforma\u00e7\u00e3o social, calcadas na forma\u00e7\u00e3o cidad\u00e3, no engajamento\u00a0 das comunidades, na atua\u00e7\u00e3o forte da divulga\u00e7\u00e3o dos canais de comunica\u00e7\u00e3o e a\u00e7\u00f5es e informa\u00e7\u00f5es preventivas, al\u00e9m do desenvolvimento do senso de pertencimento local\u201d. O projeto \u201cDe Olho no Duto\u201d contemplar\u00e1 39 comunidades do Rio de Janeiro, vizinhas \u00e0s instala\u00e7\u00f5es dos dutos da Transpetro, entre elas: Itagua\u00ed, Mangaratiba, Nova Igua\u00e7u, Maca\u00e9, Quissam\u00e3, Mag\u00e9, Paracambi, Miguel Pereira, Guapimirim, Rio das Ostras, Carapebus, Campos e Casimiro de Abreu, Paracambi. As apresenta\u00e7\u00f5es acontecer\u00e3o durante um per\u00edodo de dois anos, envolvendo mais de 600 atividades art\u00edsticas, como oficinas, cortejos, espet\u00e1culos e rodas de conversas. Ao todo, estima-se que 150 mil pessoas de todas as idades ser\u00e3o favorecidas.<\/p>\n","protected":false},"author":21,"featured_media":99424,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","footnotes":""},"categories":[13,32,31],"tags":[],"class_list":["post-99423","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-baixada","category-cultura-e-lazer","category-principais"],"_links":{"self":[{"href":"https:\/\/jornalhoje.inf.br\/wp\/wp-json\/wp\/v2\/posts\/99423","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jornalhoje.inf.br\/wp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornalhoje.inf.br\/wp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornalhoje.inf.br\/wp\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/jornalhoje.inf.br\/wp\/wp-json\/wp\/v2\/comments?post=99423"}],"version-history":[{"count":1,"href":"https:\/\/jornalhoje.inf.br\/wp\/wp-json\/wp\/v2\/posts\/99423\/revisions"}],"predecessor-version":[{"id":99425,"href":"https:\/\/jornalhoje.inf.br\/wp\/wp-json\/wp\/v2\/posts\/99423\/revisions\/99425"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jornalhoje.inf.br\/wp\/wp-json\/wp\/v2\/media\/99424"}],"wp:attachment":[{"href":"https:\/\/jornalhoje.inf.br\/wp\/wp-json\/wp\/v2\/media?parent=99423"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornalhoje.inf.br\/wp\/wp-json\/wp\/v2\/categories?post=99423"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornalhoje.inf.br\/wp\/wp-json\/wp\/v2\/tags?post=99423"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}